{"id":378,"date":"2019-08-03T10:37:36","date_gmt":"2019-08-03T08:37:36","guid":{"rendered":"https:\/\/flexider-automotive-eu.com\/product-service\/products\/decoupling-joints\/"},"modified":"2020-09-15T09:30:51","modified_gmt":"2020-09-15T07:30:51","slug":"decoupling-joints","status":"publish","type":"page","link":"https:\/\/flexider-automotive-eu.com\/it\/product-service\/products\/decoupling-joints\/","title":{"rendered":"Giunti di disaccoppiamento"},"content":{"rendered":"<h4>Disaccoppiamento dei movimenti del motore<\/h4>\n<h4>Componente a rotazione simmetrica<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-1271 size-full\" src=\"https:\/\/flexider-automotive-eu.com\/wp-content\/uploads\/2019\/09\/IMG_4284.jpg\" alt=\"\" width=\"600\" height=\"427\"><\/h4>\n<h4>Resistente alla corrosione e alla temperatura<\/h4>\n<h4>Riduzione delle risonanze del sistema<\/h4>\n<h4>Integrazione di flange secondo le esigenze del Cliente<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Disaccoppiamento dei movimenti del motore Componente a rotazione simmetrica Resistente alla corrosione e alla temperatura Riduzione delle risonanze del sistema Integrazione di flange secondo le esigenze del Cliente<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":368,"menu_order":690,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-378","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"it","enabled_languages":["en","de","it","pl"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"pl":{"title":true,"content":true,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giunti di disaccoppiamento - Flexider Automotive<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giunti di disaccoppiamento - Flexider Automotive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/\" \/>\n<meta property=\"og:site_name\" content=\"Flexider Automotive\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-15T07:30:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flexider-automotive-eu.com\/wp-content\/uploads\/2019\/09\/IMG_4284.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/de\\\/product-service\\\/products\\\/decoupling-joints\\\/\",\"url\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/de\\\/product-service\\\/products\\\/decoupling-joints\\\/\",\"name\":\"Giunti di disaccoppiamento - Flexider Automotive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/de\\\/product-service\\\/products\\\/decoupling-joints\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/de\\\/product-service\\\/products\\\/decoupling-joints\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/IMG_4284.jpg\",\"datePublished\":\"2019-08-03T08:37:36+00:00\",\"dateModified\":\"2020-09-15T07:30:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/de\\\/product-service\\\/products\\\/decoupling-joints\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/flexider-automotive-eu.com\\\/de\\\/product-service\\\/products\\\/decoupling-joints\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/de\\\/product-service\\\/products\\\/decoupling-joints\\\/#primaryimage\",\"url\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/IMG_4284.jpg\",\"contentUrl\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/IMG_4284.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/de\\\/product-service\\\/products\\\/decoupling-joints\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Product \\\/ Service\",\"item\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/de\\\/product-service\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/de\\\/product-service\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Entkoppelelemente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/#website\",\"url\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/\",\"name\":\"Flexider Automotive\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/flexider-automotive-eu.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giunti di disaccoppiamento - Flexider Automotive","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/","og_locale":"it_IT","og_type":"article","og_title":"Giunti di disaccoppiamento - Flexider Automotive","og_url":"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/","og_site_name":"Flexider Automotive","article_modified_time":"2020-09-15T07:30:51+00:00","og_image":[{"url":"https:\/\/flexider-automotive-eu.com\/wp-content\/uploads\/2019\/09\/IMG_4284.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/","url":"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/","name":"Giunti di disaccoppiamento - Flexider Automotive","isPartOf":{"@id":"https:\/\/flexider-automotive-eu.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/#primaryimage"},"image":{"@id":"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/#primaryimage"},"thumbnailUrl":"https:\/\/flexider-automotive-eu.com\/wp-content\/uploads\/2019\/09\/IMG_4284.jpg","datePublished":"2019-08-03T08:37:36+00:00","dateModified":"2020-09-15T07:30:51+00:00","breadcrumb":{"@id":"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/#primaryimage","url":"https:\/\/flexider-automotive-eu.com\/wp-content\/uploads\/2019\/09\/IMG_4284.jpg","contentUrl":"https:\/\/flexider-automotive-eu.com\/wp-content\/uploads\/2019\/09\/IMG_4284.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/decoupling-joints\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/flexider-automotive-eu.com\/"},{"@type":"ListItem","position":2,"name":"Product \/ Service","item":"https:\/\/flexider-automotive-eu.com\/de\/product-service\/"},{"@type":"ListItem","position":3,"name":"Produkte","item":"https:\/\/flexider-automotive-eu.com\/de\/product-service\/products\/"},{"@type":"ListItem","position":4,"name":"Entkoppelelemente"}]},{"@type":"WebSite","@id":"https:\/\/flexider-automotive-eu.com\/#website","url":"https:\/\/flexider-automotive-eu.com\/","name":"Flexider Automotive","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flexider-automotive-eu.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/flexider-automotive-eu.com\/it\/wp-json\/wp\/v2\/pages\/378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flexider-automotive-eu.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/flexider-automotive-eu.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/flexider-automotive-eu.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/flexider-automotive-eu.com\/it\/wp-json\/wp\/v2\/comments?post=378"}],"version-history":[{"count":10,"href":"https:\/\/flexider-automotive-eu.com\/it\/wp-json\/wp\/v2\/pages\/378\/revisions"}],"predecessor-version":[{"id":2031,"href":"https:\/\/flexider-automotive-eu.com\/it\/wp-json\/wp\/v2\/pages\/378\/revisions\/2031"}],"up":[{"embeddable":true,"href":"https:\/\/flexider-automotive-eu.com\/it\/wp-json\/wp\/v2\/pages\/368"}],"wp:attachment":[{"href":"https:\/\/flexider-automotive-eu.com\/it\/wp-json\/wp\/v2\/media?parent=378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}